{"id":50,"count":1,"description":"","link":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/","name":"Money laundering","slug":"money-laundering","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Money laundering archivos - Oliver &amp; Abogados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Money laundering archivos - Oliver &amp; Abogados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/\" \/>\n<meta property=\"og:site_name\" content=\"Oliver &amp; Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oliverabogados.es\\\/en\\\/category\\\/money-laundering\\\/\",\"url\":\"https:\\\/\\\/oliverabogados.es\\\/en\\\/category\\\/money-laundering\\\/\",\"name\":\"Money laundering archivos - Oliver &amp; Abogados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oliverabogados.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oliverabogados.es\\\/en\\\/category\\\/money-laundering\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oliverabogados.es\\\/en\\\/category\\\/money-laundering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oliverabogados.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Money laundering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oliverabogados.es\\\/#website\",\"url\":\"https:\\\/\\\/oliverabogados.es\\\/\",\"name\":\"Oliver &amp; Abogados\",\"description\":\"Especialistas en Derecho Penal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oliverabogados.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Money laundering archivos - Oliver &amp; Abogados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/","og_locale":"en_US","og_type":"article","og_title":"Money laundering archivos - Oliver &amp; Abogados","og_url":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/","og_site_name":"Oliver &amp; Abogados","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/","url":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/","name":"Money laundering archivos - Oliver &amp; Abogados","isPartOf":{"@id":"https:\/\/oliverabogados.es\/#website"},"breadcrumb":{"@id":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/oliverabogados.es\/en\/category\/money-laundering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oliverabogados.es\/en\/"},{"@type":"ListItem","position":2,"name":"Money laundering"}]},{"@type":"WebSite","@id":"https:\/\/oliverabogados.es\/#website","url":"https:\/\/oliverabogados.es\/","name":"Oliver &amp; Abogados","description":"Especialistas en Derecho Penal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oliverabogados.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/oliverabogados.es\/en\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oliverabogados.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/oliverabogados.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/oliverabogados.es\/en\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}